{"id":10909,"date":"2024-12-01T19:35:40","date_gmt":"2024-12-01T17:35:40","guid":{"rendered":"https:\/\/arhitektuuripreemiad.ee\/object\/torvandi-kooli-sisearhitektuur\/"},"modified":"2025-02-01T04:42:18","modified_gmt":"2025-02-01T02:42:18","slug":"interior-architecture-of-torvandi-school","status":"publish","type":"object","link":"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/","title":{"rendered":"Interior Architecture of T\u00f5rvandi School"},"author":[1007,2831,3094],"template":"","categories":[28],"award_cat":[883],"keywords":[847],"builder":[1066],"location":[],"client":[3095],"people":[1204,1426],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Interior Architecture of T\u00f5rvandi School - Estonian Architecture Awards<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interior Architecture of T\u00f5rvandi School - Estonian Architecture Awards\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/\" \/>\n<meta property=\"og:site_name\" content=\"Estonian Architecture Awards\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EestiArhitektuuripreemiad\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-01T02:42:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/\",\"url\":\"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/\",\"name\":\"Interior Architecture of T\u00f5rvandi School - Estonian Architecture Awards\",\"isPartOf\":{\"@id\":\"https:\/\/arhitektuuripreemiad.ee\/en\/#website\"},\"datePublished\":\"2024-12-01T17:35:40+00:00\",\"dateModified\":\"2025-02-01T02:42:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/arhitektuuripreemiad.ee\/en\/avaleht\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Objects\",\"item\":\"https:\/\/arhitektuuripreemiad.ee\/en\/object\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Interior Architecture of T\u00f5rvandi School\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arhitektuuripreemiad.ee\/en\/#website\",\"url\":\"https:\/\/arhitektuuripreemiad.ee\/en\/\",\"name\":\"Eesti arhitektuuripreemiad\",\"description\":\"Eesti parim arhitektuur, sisearhitektuur, maastikuarhitektuur\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arhitektuuripreemiad.ee\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interior Architecture of T\u00f5rvandi School - Estonian Architecture Awards","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/","og_locale":"en_US","og_type":"article","og_title":"Interior Architecture of T\u00f5rvandi School - Estonian Architecture Awards","og_url":"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/","og_site_name":"Estonian Architecture Awards","article_publisher":"https:\/\/www.facebook.com\/EestiArhitektuuripreemiad\/","article_modified_time":"2025-02-01T02:42:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/","url":"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/","name":"Interior Architecture of T\u00f5rvandi School - Estonian Architecture Awards","isPartOf":{"@id":"https:\/\/arhitektuuripreemiad.ee\/en\/#website"},"datePublished":"2024-12-01T17:35:40+00:00","dateModified":"2025-02-01T02:42:18+00:00","breadcrumb":{"@id":"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arhitektuuripreemiad.ee\/en\/object\/interior-architecture-of-torvandi-school\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arhitektuuripreemiad.ee\/en\/avaleht\/"},{"@type":"ListItem","position":2,"name":"Objects","item":"https:\/\/arhitektuuripreemiad.ee\/en\/object\/"},{"@type":"ListItem","position":3,"name":"Interior Architecture of T\u00f5rvandi School"}]},{"@type":"WebSite","@id":"https:\/\/arhitektuuripreemiad.ee\/en\/#website","url":"https:\/\/arhitektuuripreemiad.ee\/en\/","name":"Eesti arhitektuuripreemiad","description":"Eesti parim arhitektuur, sisearhitektuur, maastikuarhitektuur","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arhitektuuripreemiad.ee\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/object\/10909"}],"collection":[{"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/object"}],"about":[{"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/types\/object"}],"wp:attachment":[{"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/media?parent=10909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/categories?post=10909"},{"taxonomy":"award_cat","embeddable":true,"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/award_cat?post=10909"},{"taxonomy":"keywords","embeddable":true,"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/keywords?post=10909"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/author?post=10909"},{"taxonomy":"builder","embeddable":true,"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/builder?post=10909"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/location?post=10909"},{"taxonomy":"client","embeddable":true,"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/client?post=10909"},{"taxonomy":"people","embeddable":true,"href":"https:\/\/arhitektuuripreemiad.ee\/en\/wp-json\/wp\/v2\/people?post=10909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}